{"id":583,"date":"2021-03-09T08:59:30","date_gmt":"2021-03-09T08:59:30","guid":{"rendered":"https:\/\/iprights.org\/2021\/03\/09\/beatrice-belen-luchando-con-un-valor-inquebrantable\/"},"modified":"2026-04-30T19:53:38","modified_gmt":"2026-04-30T19:53:38","slug":"beatrice-belen-luchando-con-un-valor-inquebrantable","status":"publish","type":"post","link":"https:\/\/iprights.org\/es\/2021\/03\/09\/beatrice-belen-luchando-con-un-valor-inquebrantable\/","title":{"rendered":"Beatrice Belen: Lucha con valent\u00eda inquebrantable"},"content":{"rendered":"\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-554\" src=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1.jpg\" alt=\"Imagen tomada de: https:\/\/twitter.com\/nordisonline\/status\/1360040953549967362\" width=\"700\" height=\"700\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1.jpg 1200w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1-80x80.jpg 80w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1-768x768.jpg 768w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1-300x300.jpg 300w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1-600x600.jpg 600w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Betty-1-100x100.jpg 100w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>&nbsp;<em><span style=\"font-size: 10pt;\">imagen tomada de:&nbsp;<a href=\"https:\/\/twitter.com\/nordisonline\/status\/1360040953549967362\">https:\/\/twitter.com\/nordisonline\/status\/1360040953549967362<\/a><\/span><\/em><\/p>\n<h3><strong>BEATRICE BELEN: LUCHA CON VALENT\u00cdA INQUEBRANTABLE<\/strong><\/h3>\n<p>Betty es una lideresa ind\u00edgena del pueblo Uma en Lubuagan, Kalinga, en la regi\u00f3n de la Cordillera. Es miembro de I<em>nnabuyog<\/em>, una alianza de organizaciones de mujeres ind\u00edgenas en la Cordillera. Betty es una firme defensora del medio ambiente y de los derechos ind\u00edgenas, adem\u00e1s de trabajadora de salud comunitaria que sirve incansablemente a su comunidad. Ha dedicado su vida a proteger las tierras ancestrales y a defender los derechos de los pueblos ind\u00edgenas.  <\/p>\n<p>Belen estuvo entre quienes lideraron una barricada contra el proyecto geot\u00e9rmico de la empresa Chevron Energy en la provincia de Kalinga en 2012. En 2018, fue galardonada con el Gawad Bayani ng Kalikasan (Premio H\u00e9roe Ambiental) por su inquebrantable dedicaci\u00f3n en la defensa de sus tierras ancestrales. <\/p>\n<p>Ha sido objeto de acoso e intimidaci\u00f3n por parte de agentes del Estado desde 2015, ya que se le acusa de brindar refugio y alojar a miembros del Nuevo Ej\u00e9rcito del Pueblo, un grupo armado declarado insurgente por el gobierno de Filipinas.<\/p>\n<p>En octubre de 2020, Belen fue arrestada y detenida bajo cargos inventados. Su arresto afect\u00f3 gravemente a su familia y comunidad, ya que ella ayuda a su familia en la agricultura y en la producci\u00f3n de escobas de fibra vegetal, adem\u00e1s de asistir a sus dos nietos en su educaci\u00f3n a distancia. <\/p>\n<p>En febrero de 2021, Belen fue liberada de prisi\u00f3n despu\u00e9s de que el tribunal desestimara el cargo de posesi\u00f3n ilegal de explosivos presentado en su contra por la Polic\u00eda Nacional de Filipinas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;imagen tomada de:&nbsp;https:\/\/twitter.com\/nordisonline\/status\/1360040953549967362 BEATRICE BELEN: LUCHA CON VALENT\u00cdA INQUEBRANTABLE Betty es una lideresa ind\u00edgena del pueblo Uma en Lubuagan, Kalinga, en la regi\u00f3n de la Cordillera. Es miembro de Innabuyog, una alianza de organizaciones de mujeres ind\u00edgenas en..<\/p>\n","protected":false},"author":1,"featured_media":551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278],"tags":[211],"class_list":["post-583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-y-reportajes","tag-philippines"],"_links":{"self":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/comments?post=583"}],"version-history":[{"count":1,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/583\/revisions"}],"predecessor-version":[{"id":87375,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/583\/revisions\/87375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media\/551"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media?parent=583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/categories?post=583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/tags?post=583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}