{"id":86591,"date":"2022-08-16T05:40:17","date_gmt":"2022-08-16T05:40:17","guid":{"rendered":"https:\/\/iprights.org\/2022\/08\/16\/implicaciones-de-la-covid-19-y-la-recuperacion-economica-en-los-derechos-y-el-bienestar-de-los-pueblos-indigenas\/"},"modified":"2026-05-12T15:03:15","modified_gmt":"2026-05-12T15:03:15","slug":"implicaciones-de-la-covid-19-y-la-recuperacion-economica-en-los-derechos-y-el-bienestar-de-los-pueblos-indigenas","status":"publish","type":"post","link":"https:\/\/iprights.org\/es\/2022\/08\/16\/implicaciones-de-la-covid-19-y-la-recuperacion-economica-en-los-derechos-y-el-bienestar-de-los-pueblos-indigenas\/","title":{"rendered":"Implicaciones de la COVID-19 y la recuperaci\u00f3n econ\u00f3mica en los derechos y el bienestar de los pueblos ind\u00edgenas"},"content":{"rendered":"<p>La enfermedad por coronavirus 2019 (COVID-19), que la Organizaci\u00f3n Mundial de la Salud (OMS) declar\u00f3 como pandemia en 2020, afect\u00f3 gravemente a los pueblos ind\u00edgenas a nivel global, agravando sus condiciones preexistentes de racismo, discriminaci\u00f3n, marginaci\u00f3n, vulnerabilidad, abandono y aislamiento.<br \/>El 19 de enero de 2022, la OMS registr\u00f3 m\u00e1s de 332.6 millones de casos confirmados y 5.6 millones de muertes en todo el mundo a causa de la pandemia. Para 2019, se estimaba que la poblaci\u00f3n ind\u00edgena superaba los 476 millones de personas a nivel global.<br \/>Seg\u00fan la Organizaci\u00f3n Internacional del Trabajo (OIT), la mayor\u00eda de los pueblos ind\u00edgenas vive en la regi\u00f3n de Asia y el Pac\u00edfico (poco m\u00e1s del 70%), el 16% se encuentra en \u00c1frica y el 11.5% en Am\u00e9rica Latina y el Caribe, mientras que el resto habita en Europa y Am\u00e9rica del Norte.   <\/p>\n<p>No se dispone de datos desagregados sobre los impactos sanitarios y econ\u00f3micos de la COVID-19; sin embargo, informes de diversas agencias gubernamentales, organismos internacionales, grupos de la sociedad civil y noticias provenientes de comunidades ind\u00edgenas evidencian que los pueblos ind\u00edgenas han sido desproporcionadamente afectados por la pandemia.<br \/>La Oficina del Alto Comisionado de las Naciones Unidas para los Derechos Humanos (ACNUDH) inform\u00f3 que importantes avances estaban siendo revertidos debido a la magnitud y el alcance de las desigualdades creadas y agravadas por la pandemia. Esto incluye los derechos de los pueblos ind\u00edgenas y, desde el inicio del brote de COVID-19, numerosos informes han se\u00f1alado su impacto negativo desproporcionado a nivel global.  <\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/iprights.org\/wp-content\/uploads\/2025\/11\/Implications-of-COVID-19-and-Economic-Recovery-Plans-on-Indigenous-Peoples-Rights-and-Well-Being.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descargar el documento PDF completo<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad por coronavirus 2019 (COVID-19), que la Organizaci\u00f3n Mundial de la Salud (OMS) declar\u00f3 como pandemia en 2020, afect\u00f3 gravemente a los pueblos ind\u00edgenas a nivel global, agravando sus condiciones preexistentes de racismo, discriminaci\u00f3n, marginaci\u00f3n, vulnerabilidad, abandono..<\/p>\n","protected":false},"author":2,"featured_media":86592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[345,299],"tags":[310],"class_list":["post-86591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente-y-derechos-humanos","category-recursos","tag-otros"],"_links":{"self":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/86591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/comments?post=86591"}],"version-history":[{"count":5,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/86591\/revisions"}],"predecessor-version":[{"id":87657,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/86591\/revisions\/87657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media\/86592"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media?parent=86591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/categories?post=86591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/tags?post=86591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}