{"id":86846,"date":"2022-03-07T18:28:15","date_gmt":"2022-03-07T18:28:15","guid":{"rendered":"https:\/\/iprights.org\/2022\/03\/07\/criminalizacion-de-los-adivasis-y-el-sistema-juridico-indio\/"},"modified":"2026-04-23T04:12:26","modified_gmt":"2026-04-23T04:12:26","slug":"criminalizacion-de-los-adivasis-y-el-sistema-juridico-indio","status":"publish","type":"post","link":"https:\/\/iprights.org\/es\/2022\/03\/07\/criminalizacion-de-los-adivasis-y-el-sistema-juridico-indio\/","title":{"rendered":"Criminalizaci\u00f3n de los adivasis y el sistema jur\u00eddico indio"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/images\/articles\/resources\/Criminalisation%20of%20Adivasis%20and%20the%20Indian%20Legal%20System\/criminalization-of-adivasis-2.jpeg#joomlaImage:\/\/local-images\/articles\/resources\/Criminalisation%20of%20Adivasis%20and%20the%20Indian%20Legal%20System\/criminalization-of-adivasis-2.jpeg?width=5000&amp;height=2812\" alt=\"Criminalizaci\u00f3n de los adivasis y el sistema jur\u00eddico indio\"><\/p>\n<p>Como parte de su labor de visibilizaci\u00f3n y monitoreo de casos de criminalizaci\u00f3n, violencia e impunidad contra los pueblos ind\u00edgenas, Indigenous Peoples Rights International (IPRI) encarg\u00f3 una investigaci\u00f3n que examina las dimensiones de la criminalizaci\u00f3n de los adivasis en India.<\/p>\n<p>Escrito por Shomona Khanna, Astha Saxena, Puja y Khushboo Pareek, el libro Criminalizaci\u00f3n de los adivasis y el sistema jur\u00eddico indio ofrece una visi\u00f3n integral de este fen\u00f3meno. Las autoras emprendieron la compleja tarea de rastrear los or\u00edgenes de la criminalizaci\u00f3n de los adivasis, vincul\u00e1ndolos con la discriminaci\u00f3n y con las leyes forestales coloniales que contin\u00faan amenazando sus formas de vida hasta la actualidad. <\/p>\n<p>Este estudio, pionero en su tipo, proporciona una base s\u00f3lida para impulsar futuras iniciativas e investigaciones sobre esta problem\u00e1tica cr\u00edtica relacionada con los derechos y el bienestar de los pueblos ind\u00edgenas en India. Se espera que esta publicaci\u00f3n contribuya a inspirar los movimientos ind\u00edgenas en India y m\u00e1s all\u00e1, fortaleciendo sus esfuerzos para proteger sus derechos mediante la interacci\u00f3n con el sistema legal. Asimismo, se espera que sea un recurso \u00fatil para responsables de pol\u00edticas p\u00fablicas y personas defensoras, al generar una mayor comprensi\u00f3n sobre la importancia de fortalecer la protecci\u00f3n de los adivasis a trav\u00e9s de sistemas legales y de justicia m\u00e1s integrales y eficaces.  <\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/iprights.org\/wp-content\/uploads\/2025\/11\/Criminalisation-of-Adivasis-and-the-Indian-Legal-System-Executive-Summary.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> Descargar la publicaci\u00f3n completa<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de su labor de visibilizaci\u00f3n y monitoreo de casos de criminalizaci\u00f3n, violencia e impunidad contra los pueblos ind\u00edgenas, Indigenous Peoples Rights International (IPRI) encarg\u00f3 una investigaci\u00f3n que examina las dimensiones de la criminalizaci\u00f3n de los adivasis..<\/p>\n","protected":false},"author":3,"featured_media":86847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[318,305,299],"tags":[327,222],"class_list":["post-86846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis-y-recopilaciones-juridicas","category-criminalization-and-incarceration","category-recursos","tag-criminalization","tag-india"],"_links":{"self":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/86846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/comments?post=86846"}],"version-history":[{"count":1,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/86846\/revisions"}],"predecessor-version":[{"id":86848,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/86846\/revisions\/86848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media\/86847"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media?parent=86846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/categories?post=86846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/tags?post=86846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}