{"id":87310,"date":"2021-03-10T15:04:21","date_gmt":"2021-03-10T15:04:21","guid":{"rendered":"https:\/\/iprights.org\/2021\/03\/10\/patricia-gualinga-defendiendo-territorios-frente-a-amenazas\/"},"modified":"2021-03-10T15:04:21","modified_gmt":"2021-03-10T15:04:21","slug":"patricia-gualinga-defendiendo-territorios-frente-a-amenazas","status":"publish","type":"post","link":"https:\/\/iprights.org\/es\/2021\/03\/10\/patricia-gualinga-defendiendo-territorios-frente-a-amenazas\/","title":{"rendered":"Patricia Gualinga: Defendiendo territorios frente a amenazas"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/images\/articles\/news-and-features\/from-old-website\/patricia-gualinga-defending-territories-amid-threats.jpg#joomlaImage:\/\/local-images\/articles\/news-and-features\/from-old-website\/patricia-gualinga-defending-territories-amid-threats.jpg?width=1920&amp;height=1080\" alt=\"Patricia Gualinga: Defendiendo territorios frente a amenazas\" class=\"caption\" title=\"image from: https:\/\/amazonwatch.org\/news\/2014\/0919-why-i-march-we-need-to-leave-the-oil-in-the-ground\"><\/p>\n<p>Patricia es una l\u00edder ind\u00edgena de la comunidad Kichwa de Sarayaku, en la Amazon\u00eda ecuatoriana, y ha sido portavoz nacional e internacional en la defensa de su territorio frente a concesiones petroleras. <\/p>\n<p>Su oposici\u00f3n ha sido respondida con una creciente violencia contra la comunidad, a pesar de una sentencia favorable de la Inter-American Court of Human Rights en 2012, en la que particip\u00f3 activamente. A lo largo de estos a\u00f1os, Patricia ha enfrentado de forma constante amenazas, hostigamiento y criminalizaci\u00f3n. <\/p>\n<p>El 5 de enero de 2018, su hogar en Puyo, Ecuador, fue atacado por agresores no identificados que lanzaron piedras y rompieron ventanas, causando da\u00f1os significativos. Adem\u00e1s, Patricia recibi\u00f3 amenazas de muerte verbales. A pesar de la gravedad de los hechos, las autoridades locales y nacionales en Ecuador no investigaron el caso ni sancionaron a los responsables.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Patricia es una l\u00edder ind\u00edgena de la comunidad Kichwa de Sarayaku, en la Amazon\u00eda ecuatoriana, y ha sido portavoz nacional e internacional en la defensa de su territorio frente a concesiones petroleras. Su oposici\u00f3n ha sido respondida con..<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278],"tags":[],"class_list":["post-87310","post","type-post","status-publish","format-standard","hentry","category-noticias-y-reportajes"],"_links":{"self":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/87310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/comments?post=87310"}],"version-history":[{"count":0,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/87310\/revisions"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media?parent=87310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/categories?post=87310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/tags?post=87310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}