{"id":88281,"date":"2026-06-03T23:33:04","date_gmt":"2026-06-03T23:33:04","guid":{"rendered":"https:\/\/iprights.org\/2026\/06\/03\/transicion-justa-o-colonialismo-verde-el-impacto-de-la-transicion-energetica-de-indonesia-en-los-pueblos-indigenas\/"},"modified":"2026-06-26T19:28:20","modified_gmt":"2026-06-26T19:28:20","slug":"transicion-justa-o-colonialismo-verde-el-impacto-de-la-transicion-energetica-de-indonesia-en-los-pueblos-indigenas","status":"publish","type":"post","link":"https:\/\/iprights.org\/es\/2026\/06\/03\/transicion-justa-o-colonialismo-verde-el-impacto-de-la-transicion-energetica-de-indonesia-en-los-pueblos-indigenas\/","title":{"rendered":"\u00bfTransici\u00f3n justa o colonialismo verde? El impacto de la transici\u00f3n energ\u00e9tica de Indonesia en los Pueblos Ind\u00edgenas"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">\u00bfTransici\u00f3n justa o colonialismo verde? El impacto de la transici\u00f3n energ\u00e9tica de Indonesia en los Pueblos Ind\u00edgenas<\/h1>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\"><strong>A menudo se presenta a Indonesia como l\u00edder mundial en la transici\u00f3n hacia la energ\u00eda verde. El pa\u00eds posee alrededor del 40 % del potencial geot\u00e9rmico mundial, es el mayor productor mundial de n\u00edquel y sigue ampliando la energ\u00eda hidroel\u00e9ctrica para respaldar los sistemas de energ\u00eda limpia y la producci\u00f3n de veh\u00edculos el\u00e9ctricos. Estos recursos se promocionan como soluciones clave para la crisis clim\u00e1tica. Sin embargo, para muchos Pueblos Ind\u00edgenas, esta transici\u00f3n dista mucho de ser justa. <\/strong> <\/p>\n\n<p class=\"wp-block-paragraph\">Una de las principales razones de esta injusticia es la ausencia de una ley nacional s\u00f3lida que reconozca y proteja plenamente los derechos de los Pueblos Ind\u00edgenas. El proyecto de Ley Sobre Los Pueblos Ind\u00edgenas (RUU Masyarakat Adat), que lleva mucho tiempo retrasado, a\u00fan no ha sido aprobado. <br\/>Sin esta ley, los Pueblos Ind\u00edgenas siguen siendo jur\u00eddicamente vulnerables, con una protecci\u00f3n d\u00e9bil de sus territorios y de sus sistemas de gobernanza. Sus bosques y territorios pueden asignarse f\u00e1cilmente a proyectos mineros, geot\u00e9rmicos, de plantaciones y de energ\u00eda hidroel\u00e9ctrica en virtud de permisos estatales. En muchos casos, los Pueblos Ind\u00edgenas son tratados como ocupantes ilegales en sus propios territorios, mientras que las empresas reciben reconocimiento legal y protecci\u00f3n estatal. Este vac\u00edo legal suele conllevar el despojo de tierras, la violencia, la <strong>criminalizaci\u00f3n<\/strong> y la destrucci\u00f3n de territorios ancestrales.     <\/p>\n\n<p class=\"wp-block-paragraph\">En febrero de 2026, representantes de los Pueblos Ind\u00edgenas afectados por <strong>proyectos de transici\u00f3n energ\u00e9tica<\/strong> de toda Indonesia se reunieron en Yakarta para un taller sobre transici\u00f3n justa con el fin de reflexionar colectivamente sobre los crecientes impactos de estos proyectos en sus comunidades. Estos proyectos son la <strong>miner\u00eda de n\u00edquel, las presas hidroel\u00e9ctricas y las centrales geot\u00e9rmicas<\/strong>. El taller puso de relieve que muchos de los llamados proyectos \u00abverdes\u00bb est\u00e1n reproduciendo viejos patrones de extractivismo y exclusi\u00f3n bajo el lenguaje de la sostenibilidad.   <\/p>\n\n<p class=\"wp-block-paragraph\">Los l\u00edderes ind\u00edgenas hicieron hincapi\u00e9 en que una <strong>transici\u00f3n justa<\/strong> debe garantizar la <strong>protecci\u00f3n de los territorios ind\u00edgenas<\/strong>, l<strong>os derechos colectivos, la seguridad de las mujeres <\/strong><strong>y la autodeterminaci\u00f3n de las comunidades<\/strong>. Para los Pueblos Ind\u00edgenas, lo que est\u00e1 en juego va mucho m\u00e1s all\u00e1 de la propiedad de la tierra. Como explica el l\u00edder ind\u00edgena Romba Sombolinggi:  <\/p>\n\n<p class=\"wp-block-paragraph\">\u00abPara nosotros, como Pueblos Ind\u00edgenas, la tierra es nuestra identidad y fuente de vida. En ella se asientan nuestras costumbres y tradiciones, nuestros rituales y nuestros lugares sagrados, todos profundamente arraigados en la historia de nuestros antepasados&#8230; Perder nuestra tierra ancestral significa perder las ra\u00edces de nuestra historia y el futuro que se ha transmitido de generaci\u00f3n en generaci\u00f3n\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n de Yakarta reforz\u00f3 un llamamiento nacional compartido para rechazar el colonialismo verde y exigir que la transici\u00f3n energ\u00e9tica de Indonesia se base en la justicia, los derechos y el liderazgo de los Pueblos Ind\u00edgenas.<\/p>\n\n<h2 class=\"wp-block-heading\">Poco Leok: expansi\u00f3n geot\u00e9rmica sin el consentimiento libre, previo e informado<\/h2>\n\n<p class=\"wp-block-paragraph\">Poco Leok, en Flores, Nusa Tenggara Oriental, es uno de los ejemplos m\u00e1s claros. El proyecto de expansi\u00f3n geot\u00e9rmica de Ulumbu ha entrado en el territorio de los Pueblos Ind\u00edgenas de 10 gendang, o territorios de clanes ind\u00edgenas, en Poco Leok. Las comunidades han rechazado el proyecto desde 2011 porque no ha habido un aut\u00e9ntico C<strong>onsentimiento Libre, Previo e Informado (CLPI).<\/strong> Los permisos se expidieron sin CLPI, y los procesos se llevaron a cabo mediante intimidaci\u00f3n en lugar de consentimiento.    <\/p>\n\n<p class=\"wp-block-paragraph\">En 2023, varios ind\u00edgenas fueron citados por la polic\u00eda tras protestar contra el proyecto, lo que las comunidades consideraron una forma de criminalizaci\u00f3n e intimidaci\u00f3n. En 2025, miles de ind\u00edgenas de toda Flores se movilizaron de nuevo para rechazar la expansi\u00f3n geot\u00e9rmica y exigieron la anulaci\u00f3n del decreto del regente que aprobaba la ubicaci\u00f3n del proyecto, alegando que este se hab\u00eda emitido sin transparencia ni consentimiento de la comunidad.  <\/p>\n\n<p class=\"wp-block-paragraph\">Las mujeres ind\u00edgenas han estado en el centro de esta resistencia porque sus tierras est\u00e1n directamente vinculadas a la alimentaci\u00f3n, el agua, la medicina y la supervivencia cultural. Cuando se les arrebata la tierra, las mujeres pierden tanto la seguridad de sus medios de vida como la protecci\u00f3n cultural, al tiempo que se enfrentan a la violencia de las fuerzas de seguridad y las estructuras patriarcales. Al situarse en primera l\u00ednea para defender sus territorios ancestrales, estas mujeres se han enfrentado a una severa represi\u00f3n, que incluye violencia, criminalizaci\u00f3n e intimidaci\u00f3n por parte de las fuerzas de seguridad conjuntas  <\/p>\n\n<h2 class=\"wp-block-heading\">La miner\u00eda del n\u00edquel y la supervivencia de los O\u2019Hongana Manyawa<\/h2>\n\n<p class=\"wp-block-paragraph\">En Maluku del Norte, los Pueblos Ind\u00edgenas O\u2019Hongana Manyawa se enfrentan a graves amenazas por la miner\u00eda del n\u00edquel. La industria del n\u00edquel de Indonesia es fundamental para la c<strong>adena de suministro mundial de veh\u00edculos el\u00e9ctricos<\/strong>, pero esta econom\u00eda del \u00abmineral verde\u00bb est\u00e1 destruyendo bosques y r\u00edos en territorios ind\u00edgenas. Solo en Halmahera Oriental hay al menos 29 permisos de explotaci\u00f3n minera que abarcan m\u00e1s de 186 000 hect\u00e1reas, muchos de los cuales se solapan con los territorios de los Pueblos Ind\u00edgenas. La destrucci\u00f3n de los bosques y la contaminaci\u00f3n de los r\u00edos han reducido el espacio vital de los O\u2019Hongana Manyawa, incluidos aquellos que viven en aislamiento voluntario y que son muy vulnerables a las enfermedades, al contacto forzado y al desplazamiento.    <\/p>\n\n<p class=\"wp-block-paragraph\">La resistencia tambi\u00e9n ha tra\u00eddo consigo la criminalizaci\u00f3n. Seis l\u00edderes de la comunidad O\u2019Hongana Manyawa fueron procesados por defender sus bosques ancestrales frente a la expansi\u00f3n minera. Cuatro de ellos fueron condenados a cadena perpetua, mientras que otros dos recibieron penas de 20 a\u00f1os de prisi\u00f3n. La criminalizaci\u00f3n de los Pueblos Ind\u00edgenas refleja una realidad m\u00e1s amplia en la que la protecci\u00f3n de los bosques se considera un delito, mientras que las empresas mineras operan con el respaldo del Estado.    <\/p>\n\n<p class=\"wp-block-paragraph\">Para la comunidad O\u2019Hongana Manyawa de Halmahera, el auge de la <strong>miner\u00eda del n\u00edquel <\/strong>no es desarrollo, sino una amenaza para su supervivencia. La destrucci\u00f3n de sus bosques conlleva la criminalizaci\u00f3n y la p\u00e9rdida de sus sistemas alimentarios, r\u00edos, plantas medicinales y de toda su identidad cultural. <\/p>\n\n<h2 class=\"wp-block-heading\">Las comunidades de Toraja se enfrentan al desarrollo geot\u00e9rmico<\/h2>\n\n<p class=\"wp-block-paragraph\">En Toraja, en el sur de Sulawesi, el desarrollo geot\u00e9rmico ya suscita serias preocupaciones. El proyecto geot\u00e9rmico previsto, de 12 979 hect\u00e1reas, amenaza con afectar a un subdistrito y a cuatro territorios de Pueblos Ind\u00edgenas. Estas zonas incluyen bosques sagrados, cementerios, tierras agr\u00edcolas y fuentes de agua que son fundamentales tanto para la pr\u00e1ctica espiritual como para la vida cotidiana.   <\/p>\n\n<p class=\"wp-block-paragraph\">Para las comunidades de Toraja, la cuesti\u00f3n no es solo el da\u00f1o medioambiental, sino tambi\u00e9n la protecci\u00f3n de la identidad ancestral y la gobernanza consuetudinaria. Toraja demuestra que una transici\u00f3n justa debe comenzar antes de que se inicie la extracci\u00f3n, no solo despu\u00e9s de que las comunidades hayan sido desplazadas. <\/p>\n\n<h2 class=\"wp-block-heading\">El proyecto geot\u00e9rmico de Hululais y sus impactos ambientales<\/h2>\n\n<p class=\"wp-block-paragraph\">En Hululais, Bengkulu, el desarrollo geot\u00e9rmico llevado a cabo por PT Pertamina Geothermal Energy (PT PGE) ha tenido graves repercusiones para los Pueblos Ind\u00edgenas. El proyecto se encuentra dentro del bosque protegido de Bukit Daun, cerca de asentamientos comunitarios, tierras de cultivo y zonas consuetudinarias de las que depende la subsistencia de la poblaci\u00f3n.  <\/p>\n\n<p class=\"wp-block-paragraph\">Durante la exploraci\u00f3n en 2018, las actividades de perforaci\u00f3n provocaron deslizamientos de tierra que causaron muertes y da\u00f1aron estanques pisc\u00edcolas, arrozales y plantaciones. Las cuencas hidrogr\u00e1ficas tambi\u00e9n resultaron da\u00f1adas, lo que redujo el caudal de los r\u00edos y contamin\u00f3 las fuentes de agua potable de las aldeas cercanas. Las comunidades informaron de movimientos de tierra y de vapor caliente que sal\u00eda del suelo, lo que sec\u00f3 y quem\u00f3 los cultivos de sus huertos. Al menos seis aldeas con m\u00e1s de 5.500 personas se han visto afectadas, lo que demuestra que los proyectos geot\u00e9rmicos pueden causar graves da\u00f1os ambientales y sociales cuando se ignoran los derechos de los Pueblos Ind\u00edgenas.   <\/p>\n\n<h2 class=\"wp-block-heading\">La presa de Lambo y la criminalizaci\u00f3n de la resistencia ind\u00edgena<\/h2>\n\n<p class=\"wp-block-paragraph\">Los proyectos hidroel\u00e9ctricos en Rendu reflejan el mismo patr\u00f3n de injusticia. La presa de Lambo, actualmente en proyecto, amenaza los territorios tradicionales de los Pueblos Ind\u00edgenas rendu, ndora y lambo, donde los r\u00edos son fundamentales para los sistemas agr\u00edcolas, la seguridad alimentaria y la vida espiritual. Las comunidades temen perder tierras agr\u00edcolas, fuentes de agua, lugares sagrados y territorio ancestral que sustentan tanto sus medios de vida como su identidad cultural.   <\/p>\n\n<p class=\"wp-block-paragraph\">La criminalizaci\u00f3n y la violencia han acompa\u00f1ado a la resistencia al proyecto. En 2021, mujeres ind\u00edgenas denunciaron violencia, intimidaci\u00f3n, acoso sexual y allanamiento de tierras ancestrales por parte de la polic\u00eda, la Brimob, el TNI y las autoridades locales que escoltaban a los equipos de prospecci\u00f3n del proyecto de la presa. En 2022, la polic\u00eda detuvo por la fuerza a 24 ind\u00edgenas de Rendu, 23 hombres y una mujer, despu\u00e9s de que bloquearan actividades relacionadas con el proyecto de la presa, y miembros de la comunidad denunciaron haber sido golpeados durante las detenciones. Estas acciones muestran c\u00f3mo los proyectos hidroel\u00e9ctricos suelen imponerse mediante la represi\u00f3n en lugar del di\u00e1logo.   <\/p>\n\n<h2 class=\"wp-block-heading\">C\u00f3mo es una transici\u00f3n justa basada en los derechos<\/h2>\n\n<p class=\"wp-block-paragraph\">Estos casos revelan que el problema fundamental no radica en la energ\u00eda renovable en s\u00ed misma, sino en las formas coercitivas y excluyentes con las que se planifican y ejecutan estos proyectos. Una transici\u00f3n verdaderamente justa debe centrarse en los derechos humanos y dar prioridad a las personas por encima de los objetivos de sostenibilidad no regulados.  <\/p>\n\n<p class=\"wp-block-paragraph\">Los Pueblos Ind\u00edgenas deben poder ejercer libremente, sin amenazas, intimidaci\u00f3n ni acoso, su derecho a decidir sobre las actividades que afectan a sus tierras ancestrales. En este contexto, el <strong>CLPI<\/strong> debe defenderse como un derecho humano sustantivo y no como una mera formalidad procesal que ignora las opiniones, preocupaciones y decisiones colectivas de las comunidades ind\u00edgenas afectadas. Adem\u00e1s, debe ponerse fin al uso de leyes discriminatorias para criminalizar a los Pueblos Ind\u00edgenas. Pedimos mecanismos de protecci\u00f3n espec\u00edficos para las mujeres ind\u00edgenas frente a la violencia, el acoso y la marginaci\u00f3n sist\u00e9mica.    <\/p>\n\n<p class=\"wp-block-paragraph\">Y lo que es m\u00e1s importante, Indonesia debe aprobar una Ley de Pueblos Ind\u00edgenas s\u00f3lida que reconozca expl\u00edcitamente los territorios de los Pueblos Ind\u00edgenas, los derechos colectivos y los sistemas de gobernanza tradicionales. Sin un reconocimiento y una protecci\u00f3n jur\u00eddicos s\u00f3lidos y una aplicaci\u00f3n adecuada, la transici\u00f3n verde corre el riesgo de convertirse en otra forma de explotaci\u00f3n bajo una nueva etiqueta. <\/p>\n\n<p class=\"wp-block-paragraph\">La riqueza geot\u00e9rmica, de n\u00edquel e hidroel\u00e9ctrica de Indonesia no debe utilizarse para impulsar el \u00ab<strong>colonialismo verde<\/strong>\u00bb. Para evitarlo, <strong>una transici\u00f3n verdaderamente justa debe basarse firmemente en<\/strong>: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Derechos territoriales de los Pueblos Ind\u00edgenas y Consentimiento Libre, Previo e Informado<\/strong>: Garantizar el reconocimiento legal y formal de los territorios ind\u00edgenas, as\u00ed como la correcta aplicaci\u00f3n del CLPI, para prevenir los desplazamientos y el acaparamiento de tierras.<\/li>\n\n\n\n<li>Protecci\u00f3n de las <strong>mujeres ind\u00edgenas<\/strong>: Proteger a las mujeres ind\u00edgenas de los impactos sociales, culturales y econ\u00f3micos desproporcionados derivados de proyectos extractivos no controlados.<\/li>\n\n\n\n<li>Respeto y protecci\u00f3n de la <strong>gobernanza ind\u00edgena<\/strong>: Garantizar que las comunidades ind\u00edgenas tengan el poder de decidir colectivamente sobre el uso de sus tierras, territorios y recursos, as\u00ed como sobre su propio futuro y sus v\u00edas de desarrollo, con base en sus sistemas de gobernanza, cultura y modos de vida ind\u00edgenas.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Datos clave<\/h2>\n\n<ol class=\"wp-block-list\">\n<li>Indonesia posee aproximadamente el 40 % del potencial de energ\u00eda geot\u00e9rmica del mundo.<\/li>\n\n\n\n<li>Indonesia es el mayor productor mundial de n\u00edquel.<\/li>\n\n\n\n<li>M\u00e1s de 186 000 hect\u00e1reas en Halmahera Oriental est\u00e1n cubiertas por permisos de explotaci\u00f3n minera.<\/li>\n\n\n\n<li>Al menos 5.500 personas se ven afectadas por el desarrollo geot\u00e9rmico en Hululais.<\/li>\n\n\n\n<li>Las comunidades ind\u00edgenas de toda Indonesia denuncian la criminalizaci\u00f3n, el despojo de tierras y la falta de Consentimiento Libre, Previo e Informado en relaci\u00f3n con los proyectos de transici\u00f3n energ\u00e9tica.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTransici\u00f3n justa o colonialismo verde? El impacto de la transici\u00f3n energ\u00e9tica de Indonesia en los Pueblos Ind\u00edgenas A menudo se presenta a Indonesia como l\u00edder mundial en la transici\u00f3n hacia la energ\u00eda verde. El pa\u00eds posee alrededor del..<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[345,372,278],"tags":[373,474,108,235,340],"class_list":["post-88281","post","type-post","status-publish","format-standard","hentry","category-medio-ambiente-y-derechos-humanos","category-noticias-y-eventos","category-noticias-y-reportajes","tag-cambio-climatico","tag-conocimientos-de-los-pueblos-indigenas","tag-indonesia","tag-just-transition"],"_links":{"self":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/88281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/comments?post=88281"}],"version-history":[{"count":1,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/88281\/revisions"}],"predecessor-version":[{"id":88282,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/88281\/revisions\/88282"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media?parent=88281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/categories?post=88281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/tags?post=88281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}