{"id":927,"date":"2021-04-26T08:24:59","date_gmt":"2021-04-26T08:24:59","guid":{"rendered":"https:\/\/iprights.org\/2021\/04\/26\/es-global-report-2021\/"},"modified":"2026-04-29T04:25:00","modified_gmt":"2026-04-29T04:25:00","slug":"es-global-report-2021","status":"publish","type":"post","link":"https:\/\/iprights.org\/es\/2021\/04\/26\/es-global-report-2021\/","title":{"rendered":"Defendiendo nuestras tierras, territorios y recursos naturales en medio de la pandemia de COVID-19: informe anual"},"content":{"rendered":"<p>Informe anual sobre la criminalizaci\u00f3n, la violencia y la impunidad contra los pueblos ind\u00edgenas<\/p>\n<p>  <!--more-->  <\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-785\" src=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2.jpg\" alt=\"IPRI annual criminalisation report FINAL page 001\" width=\"638\" height=\"826\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2.jpg 1978w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2-768x994.jpg 768w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2-1187x1536.jpg 1187w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2-1582x2048.jpg 1582w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2-1200x1553.jpg 1200w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/04\/Annual-Report-Final-scaled-2-600x777.jpg 600w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/p>\n<p>De 2016 a 2018, los Relatores Especiales sobre la situaci\u00f3n de las personas defensoras de derechos humanos, sobre derechos humanos y medio ambiente, y sobre los derechos de los pueblos ind\u00edgenas, dieron la alarma sobre una \u201ccrisis global\u201d en desarrollo de ataques contra las personas defensoras de derechos humanos ambientales, que afectaba de manera desproporcionada a los pueblos ind\u00edgenas. Con la esperanza de contar con una plataforma global para que los pueblos y movimientos ind\u00edgenas aborden colectivamente esta crisis mundial, se cre\u00f3 la Iniciativa Global para Abordar y Prevenir la Criminalizaci\u00f3n, la Violencia y la Impunidad contra los Pueblos Ind\u00edgenas (en adelante, la Iniciativa Global). La Indigenous Peoples Rights International fue establecida para supervisar la Iniciativa Global. IPRI es una organizaci\u00f3n global sin fines de lucro de pueblos ind\u00edgenas que trabaja para proteger sus derechos y para unir y amplificar el llamado a la justicia de las v\u00edctimas de la criminalizaci\u00f3n y la impunidad. Los miembros del Consejo Global de IPRI son activistas y l\u00edderes ind\u00edgenas de todo el mundo.  <\/p>\n<p>Un componente central de la Iniciativa Global es el monitoreo y la documentaci\u00f3n de incidentes de criminalizaci\u00f3n, violencia e impunidad contra los pueblos ind\u00edgenas. Parte de este componente es la creaci\u00f3n de una base de datos para registrar estos incidentes y la publicaci\u00f3n de un informe anual que refleje los datos recopilados.  Sin embargo, dado que la base de datos se encuentra actualmente en fase de desarrollo, este informe anual se centra m\u00e1s en las distintas dimensiones de la criminalizaci\u00f3n y la impunidad, bas\u00e1ndose en los contextos nacionales y los estudios de caso de los seis pa\u00edses prioritarios de la Indigenous Peoples Rights International: Rep\u00fablica Democr\u00e1tica del Congo (RDC), Brasil, Colombia, M\u00e9xico, India y Filipinas.<\/p>\n<p>Los contextos nacionales y los estudios de caso se desarrollaron en colaboraci\u00f3n con los socios de la Indigenous Peoples Rights International, a saber: Programme Int\u00e9gr\u00e9 Pour Le D\u00e9veloppement du Peuple Pygm\u00e9e au Kivu para la RDC, Articula\u00e7\u00e3o dos Povos Ind\u00edgenas do Brasil para Brasil, Centro de Derechos Humanos de la Monta\u00f1a Tlachinollan para M\u00e9xico y Panaghiusa Network para Filipinas. Para el texto sobre India, se contrat\u00f3 a un consultor de investigaci\u00f3n ind\u00edgena y, para Colombia, dos consultores \u2014guiados por la miembro del consejo de IPRI, Leonor Zalabata\u2014 ayudaron a finalizar el contexto nacional y los estudios de caso. <\/p>\n<p>Los estudios de caso son ilustraciones espec\u00edficas de la situaci\u00f3n general descrita brevemente en los contextos nacionales. Estos ofrecen una visi\u00f3n puntual de la situaci\u00f3n de los pueblos ind\u00edgenas y de las consecuencias que han enfrentado en relaci\u00f3n con la defensa de sus derechos colectivos sobre sus tierras, territorios y recursos, as\u00ed como de su derecho a la autodeterminaci\u00f3n y al autogobierno, en el contexto de la pandemia de COVID-19 que comenz\u00f3 a principios de 2020. <\/p>\n<p>A partir de los contextos nacionales y los estudios de caso, este informe anual presenta los patrones de amenazas y hostigamientos que a menudo conducen a la criminalizaci\u00f3n y\/o a los asesinatos. Asimismo, explora la criminalizaci\u00f3n m\u00e1s all\u00e1 de la definici\u00f3n com\u00fan de abuso de la ley. <\/p>\n<p>La criminalizaci\u00f3n se define como el uso indebido de las leyes penales que implica la manipulaci\u00f3n del poder punitivo del Estado y de actores no estatales con el fin de controlar, castigar y\/o impedir el ejercicio del derecho a defender los derechos humanos.[4] Ocurre, por ejemplo, cuando las personas defensoras son acusadas injustamente de cometer delitos como resultado de sus actividades, priv\u00e1ndolas as\u00ed de su libertad en momentos cruciales para la defensa de sus causas, as\u00ed como someti\u00e9ndolas a procesos sin las debidas garant\u00edas procesales.  En consideraci\u00f3n de los contextos nacionales y los estudios de caso analizados en este informe, la criminalizaci\u00f3n tambi\u00e9n puede ocurrir cuando actores estatales y no estatales utilizan y abusan de su posici\u00f3n de poder, incluso sin recurrir a leyes o pol\u00edticas, para controlar, castigar y\/o impedir el ejercicio del derecho de los pueblos ind\u00edgenas a defender sus derechos individuales y colectiv<\/p>\n<p>El informe tambi\u00e9n presenta la relaci\u00f3n entre la discriminaci\u00f3n arraigada y la impunidad de la que gozan quienes atacan a los pueblos ind\u00edgenas y su labor en la defensa de sus derechos individuales y de sus derechos colectivos \u2014incluidos los derechos sobre sus tierras, la autodeterminaci\u00f3n y el autogobierno\u2014 mientras enfrentan el impacto de la crisis sanitaria.<\/p>\n<p>Adem\u00e1s de los contextos nacionales y los estudios de caso, el informe anual tambi\u00e9n basa sus hallazgos en informes y art\u00edculos de noticias sobre las violaciones de los derechos de los pueblos ind\u00edgenas en el a\u00f1o 2020, incluido el uso indebido de leyes y pol\u00edticas impuestas para abordar los impactos de la pandemia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informe anual sobre la criminalizaci\u00f3n, la violencia y la impunidad contra los pueblos ind\u00edgenas<\/p>\n","protected":false},"author":1,"featured_media":921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[260],"tags":[],"class_list":["post-927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications"],"_links":{"self":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/comments?post=927"}],"version-history":[{"count":1,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/927\/revisions"}],"predecessor-version":[{"id":87274,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/posts\/927\/revisions\/87274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media\/921"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/media?parent=927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/categories?post=927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/es\/wp-json\/wp\/v2\/tags?post=927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}