{"id":381,"date":"2021-01-25T03:00:55","date_gmt":"2021-01-25T03:00:55","guid":{"rendered":"https:\/\/iprights.org\/2021\/01\/25\/le-24-janvier-est-la-journee-internationale-de-l-education\/"},"modified":"2026-05-03T22:01:53","modified_gmt":"2026-05-03T22:01:53","slug":"le-24-janvier-est-la-journee-internationale-de-l-education","status":"publish","type":"post","link":"https:\/\/iprights.org\/fr\/2021\/01\/25\/le-24-janvier-est-la-journee-internationale-de-l-education\/","title":{"rendered":"Le 24 janvier est la Journ\u00e9e internationale de l\u2019\u00e9ducation."},"content":{"rendered":"<\/div>\n<div>&nbsp;<img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-358\" src=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/01\/Jan_24_-_Education_Day-1.jpg\" alt=\"Jan 24 Education Day\" width=\"940\" height=\"788\" srcset=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/01\/Jan_24_-_Education_Day-1.jpg 940w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/01\/Jan_24_-_Education_Day-1-768x644.jpg 768w, https:\/\/iprights.org\/wp-content\/uploads\/2021\/01\/Jan_24_-_Education_Day-1-600x503.jpg 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/div>\n<div>&nbsp;<\/div>\n<div>L\u2019Assembl\u00e9e g\u00e9n\u00e9rale des United Nations a adopt\u00e9 une r\u00e9solution proclamant le 24 janvier comme Journ\u00e9e internationale de l\u2019\u00e9ducation, en reconnaissance du r\u00f4le de l\u2019\u00e9ducation pour la paix et le d\u00e9veloppement. Le droit \u00e0 l\u2019\u00e9ducation est un droit humain universel. Pourtant, de nombreux peuples autochtones sont priv\u00e9s d\u2019un acc\u00e8s \u00e0 une \u00e9ducation de qualit\u00e9, inclusive et respectueuse de leur culture.  &nbsp;<\/div>\n<div>Aux Philippines, les peuples autochtones ont travaill\u00e9 ensemble pour cr\u00e9er des \u00e9coles lumad destin\u00e9es aux jeunes et aux enfants autochtones. Cependant, ces \u00e9coles ont \u00e9t\u00e9 ferm\u00e9es par le gouvernement, et les peuples autochtones sont attaqu\u00e9s et criminalis\u00e9s pour avoir d\u00e9fendu leurs \u00e9tablissements scolaires et affirm\u00e9 leur droit \u00e0 l\u2019\u00e9ducation. &nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; L\u2019Assembl\u00e9e g\u00e9n\u00e9rale des United Nations a adopt\u00e9 une r\u00e9solution proclamant le 24 janvier comme Journ\u00e9e internationale de l\u2019\u00e9ducation, en reconnaissance du r\u00f4le de l\u2019\u00e9ducation pour la paix et le d\u00e9veloppement. Le droit \u00e0 l\u2019\u00e9ducation est un..<\/p>\n","protected":false},"author":1,"featured_media":355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[279],"tags":[242,221],"class_list":["post-381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-et-caracteristiques","tag-multimedia","tag-news"],"_links":{"self":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":1,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"predecessor-version":[{"id":87470,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/381\/revisions\/87470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media\/355"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}