{"id":584,"date":"2021-03-09T08:59:30","date_gmt":"2021-03-09T08:59:30","guid":{"rendered":"https:\/\/iprights.org\/2021\/03\/09\/rose-hayahay-defendre-les-droits-des-autochtones-a-travers-l-education\/"},"modified":"2026-04-30T19:54:16","modified_gmt":"2026-04-30T19:54:16","slug":"rose-hayahay-defendre-les-droits-des-autochtones-a-travers-l-education","status":"publish","type":"post","link":"https:\/\/iprights.org\/fr\/2021\/03\/09\/rose-hayahay-defendre-les-droits-des-autochtones-a-travers-l-education\/","title":{"rendered":"Rose Hayahay: D\u00e9fense des droits autochtones par l\u2019\u00e9ducation"},"content":{"rendered":"\n<p style=\"text-align: center;\">&nbsp;<strong><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-561\" src=\"https:\/\/iprights.org\/wp-content\/uploads\/2021\/03\/Rose-1.png\" alt=\"Rose Hayahay (image from: https:\/\/kodao.org\/teacher-rose-kabataang-guro-ng-mga-lumad\/)\" width=\"700\" height=\"393\" style=\"display: block; margin-left: auto; margin-right: auto;\"><\/strong><span style=\"font-size: 10pt;\"><em>image de:&nbsp;<a href=\"https:\/\/kodao.org\/teacher-rose-kabataang-guro-ng-mga-lumad\/\">https:\/\/kodao.org\/teacher-rose-kabataang-guro-ng-mga-lumad\/<\/a><\/em><\/span><\/p>\n<h3><strong>Rose Hayahay: D\u00e9fense des droits autochtones par l\u2019\u00e9ducation<\/strong><\/h3>\n<h5><strong>\u00abLes peuples autochtones veulent \u00e9tudier; ils veulent \u00eatre \u00e9duqu\u00e9s. Mais ils n\u2019ont pas d\u2019\u00e9coles dans leurs communaut\u00e9s\u00bb<\/strong><\/h5>\n<p>Rose Hayahay, originaire de Davao de Oro, est une enseignante b\u00e9n\u00e9vole de 23 ans \u00e0 l\u2019\u00e9cole Lumad Bakwit \u00e0 Manille, aux Philippines. Elle enseigne la lecture, l\u2019\u00e9criture et les math\u00e9matiques aux \u00e9l\u00e8ves Lumad depuis 2016. <\/p>\n<p>L\u2019enseignante Rose a enseign\u00e9 au Community Technical College of Southeastern Mindanao (CTCSM), un \u00e9tablissement communautaire situ\u00e9 \u00e0 Davao de Oro qui accueille plus de 300 \u00e9tudiants Lumad et issus de familles paysannes.<\/p>\n<p>Malgr\u00e9 leurs contributions prometteuses \u00e0 l\u2019\u00e9ducation des peuples autochtones, les \u00e9coles Lumad ont \u00e9t\u00e9 ferm\u00e9es de force par le gouvernement des Philippines. En mars 2020, le CTCSM a cess\u00e9 ses activit\u00e9s apr\u00e8s que le D\u00e9partement de l\u2019\u00e9ducation de la r\u00e9gion 11 a ordonn\u00e9 le non-renouvellement de son permis et sa fermeture en mai 2020. <\/p>\n<p>Face aux conditions r\u00e9pressives, les enseignants b\u00e9n\u00e9voles et les \u00e9tudiants Lumad sont rest\u00e9s d\u00e9termin\u00e9s. Ils se sont rendus dans diff\u00e9rentes villes du pays et ont mis en place des \u00e9coles Lumad Bakwit afin de continuer \u00e0 d\u00e9fendre leur droit \u00e0 l\u2019\u00e9ducation. <\/p>\n<p>De son c\u00f4t\u00e9, l\u2019enseignante Rose a continu\u00e9 \u00e0 enseigner \u00e0 ses \u00e9l\u00e8ves malgr\u00e9 l\u2019intensification des attaques contre les Lumad et leurs \u00e9coles. Elle a \u00e9galement subi des attaques personnelles, notamment l\u2019enl\u00e8vement de sa m\u00e8re en 2018 afin de la contraindre \u00e0 se rendre, ainsi que des campagnes constantes de \u00ab red-tagging \u00bb et de d\u00e9nigrement sur les r\u00e9seaux sociaux. <\/p>\n<p>L\u2019enseignante Rose d\u00e9clare qu\u2019elle a l\u2019intention de se battre jusqu\u2019\u00e0 ce qu\u2019ils puissent tous retourner sur leurs terres en toute s\u00e9curit\u00e9 et poursuivre leur \u00e9ducation dans la paix.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;image de:&nbsp;https:\/\/kodao.org\/teacher-rose-kabataang-guro-ng-mga-lumad\/ Rose Hayahay: D\u00e9fense des droits autochtones par l\u2019\u00e9ducation \u00abLes peuples autochtones veulent \u00e9tudier; ils veulent \u00eatre \u00e9duqu\u00e9s. Mais ils n\u2019ont pas d\u2019\u00e9coles dans leurs communaut\u00e9s\u00bb Rose Hayahay, originaire de Davao de Oro, est une enseignante b\u00e9n\u00e9vole..<\/p>\n","protected":false},"author":1,"featured_media":576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[279],"tags":[254],"class_list":["post-584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-et-caracteristiques","tag-philippines"],"_links":{"self":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/comments?post=584"}],"version-history":[{"count":1,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/584\/revisions"}],"predecessor-version":[{"id":87377,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/584\/revisions\/87377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media\/576"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media?parent=584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/categories?post=584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/tags?post=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}