{"id":85546,"date":"2024-07-09T06:43:48","date_gmt":"2024-07-09T06:43:48","guid":{"rendered":"https:\/\/iprights.org\/2024\/07\/09\/tigres-conservation-et-droits-des-peuples-autochtones\/"},"modified":"2026-04-01T22:49:38","modified_gmt":"2026-04-01T22:49:38","slug":"tigres-conservation-et-droits-des-peuples-autochtones","status":"publish","type":"post","link":"https:\/\/iprights.org\/fr\/2024\/07\/09\/tigres-conservation-et-droits-des-peuples-autochtones\/","title":{"rendered":"Tigres, conservation et droits des peuples autochtones"},"content":{"rendered":"<p>Tigres, conservation et droits des peuples autochtones Derri\u00e8re la conservation active et la renaissance de la population de tigres en d\u00e9clin en Inde, persistent des probl\u00e8mes et des cas d&rsquo;anomalies, d&rsquo;irr\u00e9gularit\u00e9s et de violations flagrantes des droits, de violences en d\u00e9tention, de tortures, de faux proc\u00e8s contre les peuples autochtones et d&rsquo;expulsions forc\u00e9es de ces derniers.&nbsp;&nbsp;<\/p>\n<p>Avec le lancement du projet Tiger en avril 1973 pour promouvoir la protection et la gestion des tigres, qui comprenait initialement neuf r\u00e9serves de tigres s&rsquo;\u00e9tendant sur 18 278 m\u00b2, 41 086 familles vivant \u00e0 l&rsquo;int\u00e9rieur de ces r\u00e9serves de tigres dans 496 villages \u00e9taient susceptibles d&rsquo;\u00eatre d\u00e9plac\u00e9es. Aujourd&rsquo;hui encore, les peuples autochtones et les communaut\u00e9s locales continuent d&rsquo;\u00eatre expuls\u00e9s de leurs terres ancestrales au nom de la conservation. &nbsp;<\/p>\n<p>Bien que des progr\u00e8s significatifs aient \u00e9t\u00e9 r\u00e9alis\u00e9s dans la conservation des tigres dans le pays et que l&rsquo;Inde soit le seul pays o\u00f9 la population de tigres augmente par rapport \u00e0 d&rsquo;autres nations o\u00f9 elle stagne ou d\u00e9cline, environ 18 493 familles ont \u00e9t\u00e9 relocalis\u00e9es et d\u00e9plac\u00e9es de 215 villages \u00e0 travers l&rsquo;Inde. Pranab Doley, d\u00e9fenseur des droits de l&rsquo;homme des peuples autochtones, est conscient de l&rsquo;\u00e9coblanchiment du projet Tiger. Il a r\u00e9cemment particip\u00e9 \u00e0 l&rsquo;organisation d&rsquo;une mobilisation en r\u00e9action \u00e0 la c\u00e9l\u00e9bration par le gouvernement indien de 50 ans de conservation, alors que de nombreuses violations des droits de l&rsquo;homme ont \u00e9t\u00e9 commises \u00e0 l&rsquo;encontre des peuples et des communaut\u00e9s autochtones.  &nbsp;<\/p>\n<p>En raison de sa participation active \u00e0 la d\u00e9nonciation et \u00e0 l&rsquo;opposition au projet, il a \u00e9t\u00e9 harcel\u00e9 et vilipend\u00e9 par l&rsquo;\u00c9tat. M. Doley a commenc\u00e9 \u00e0 travailler avec les agriculteurs, les travailleurs et les populations indig\u00e8nes de l&rsquo;Assam, dans le nord-est de l&rsquo;Inde, apr\u00e8s avoir termin\u00e9 ses \u00e9tudes \u00e0 l&rsquo;universit\u00e9. Il appartient \u00e0 la communaut\u00e9 tribale Mising, qui compte environ 7 millions de personnes. Il travaille sur la question des droits fonciers, en particulier pour les personnes install\u00e9es dans le parc national de Kaziranga, qui n&rsquo;ont pas re\u00e7u de titres de propri\u00e9t\u00e9 et ont \u00e9t\u00e9 expuls\u00e9es par le gouvernement. Il a \u00e9t\u00e9 sensibilis\u00e9 aux questions de violations des droits de l&rsquo;homme r\u00e9sultant de la militarisation du parc national pour prot\u00e9ger le rhinoc\u00e9ros \u00e0 une corne.    &nbsp;<\/p>\n<p>L&rsquo;une des questions cruciales qu&rsquo;il a abord\u00e9es \u00e9tait l&rsquo;assassinat d&rsquo;individus de la communaut\u00e9 p\u00e9riph\u00e9rique qui avaient \u00e9t\u00e9 accus\u00e9s et tu\u00e9s en tant que braconniers. Ils ont transmis le dossier \u00e0 la Commission nationale des droits de l&rsquo;homme de l&rsquo;Inde et ont travaill\u00e9 sur cette affaire en 2016. La BBC et les m\u00e9dias nationaux ont repris leur histoire, mais le harc\u00e8lement et l&rsquo;intimidation ont \u00e9galement commenc\u00e9. Outre les d\u00e9placements, plusieurs cas d&rsquo;expulsion forc\u00e9e et de criminalisation ont \u00e9t\u00e9 enregistr\u00e9s. Des cas ont \u00e9t\u00e9 signal\u00e9s o\u00f9 le d\u00e9partement des for\u00eats, ainsi que l&rsquo;agence de conservation des for\u00eats sauvages, ont fait pression et o\u00f9 les forces de protection des tigres ont harcel\u00e9 des familles et des chefs de communaut\u00e9 qui d\u00e9non\u00e7aient le d\u00e9placement de leur communaut\u00e9.    &nbsp;<\/p>\n<p>De nombreux chefs de tribus ont \u00e9t\u00e9 accus\u00e9s de fausses accusations ; d&rsquo;autres ont \u00e9t\u00e9 tortur\u00e9s et assassin\u00e9s pour menacer et forcer les communaut\u00e9s \u00e0 accepter les conditions de relocalisation. L&rsquo;argent des compensations pour les programmes de r\u00e9installation est souvent corrompu par les fonctionnaires forestiers. Il est \u00e9galement prouv\u00e9 que les populations autochtones sont utilis\u00e9es comme boucs \u00e9missaires dans les activit\u00e9s de braconnage pour prot\u00e9ger le syndicat organis\u00e9 des braconniers avec l&rsquo;aide des politiciens et du d\u00e9partement des for\u00eats.  &nbsp;<\/p>\n<p>Doley a demand\u00e9 le soutien du Legal Defense and Sanctuary Fund d&rsquo;Indigenous Peoples&rsquo; Rights International (IPRI) lorsqu&rsquo;il a \u00e9t\u00e9 confront\u00e9 \u00e0 la criminalisation et \u00e0 l&rsquo;intimidation de la part de l&rsquo;\u00c9tat. Doley fait l&rsquo;objet de cinq proc\u00e9dures p\u00e9nales, dont deux ont \u00e9t\u00e9 abandonn\u00e9es. Il a \u00e9t\u00e9 acquitt\u00e9 par les tribunaux de district et de subdivision, mais deux nouvelles affaires ont \u00e9t\u00e9 d\u00e9pos\u00e9es contre lui au cours du dernier trimestre 2022.  Il a demand\u00e9 un nouveau passeport en 2021 au minist\u00e8re de l&rsquo;int\u00e9rieur, mais son passeport a \u00e9t\u00e9 retenu jusqu&rsquo;en mai 2023. Le minist\u00e8re de l&rsquo;int\u00e9rieur a mis en doute sa nationalit\u00e9. Il pense qu&rsquo;il s&rsquo;agit de repr\u00e9sailles du gouvernement \u00e0 son activisme et \u00e0 sa deuxi\u00e8me place aux \u00e9lections locales, o\u00f9 il \u00e9tait candidat de l&rsquo;opposition sous l&rsquo;\u00e9gide du Parti communiste indien. Il s&rsquo;est pr\u00e9sent\u00e9 aux \u00e9lections l\u00e9gislatives au niveau de l&rsquo;\u00c9tat, o\u00f9 le parti au pouvoir \u00e9tait menac\u00e9 par de nouveaux et jeunes candidats.     &nbsp;<\/p>\n<p>Il esp\u00e9rait que sa participation aux \u00e9lections locales le mettrait \u00e0 l&rsquo;abri des intimidations, mais il a \u00e9t\u00e9 arr\u00eat\u00e9 quatre fois depuis les \u00e9lections de 2021. M. Doley b\u00e9n\u00e9ficie du soutien total de sa communaut\u00e9 et appr\u00e9cie les relations \u00e9troites qu&rsquo;il entretient avec elle. Il affirme que \u00ab\u00a0le gouvernement ne sert que ses propres int\u00e9r\u00eats\u00a0\u00bb. Il soup\u00e7onne le gouvernement d&rsquo;\u00eatre impliqu\u00e9 dans des pratiques de braconnage organis\u00e9. Il ajoute : \u00ab\u00a0Le harc\u00e8lement par le biais de fausses accusations est une strat\u00e9gie classique visant \u00e0 restreindre les communaut\u00e9s marginalis\u00e9es et \u00e0 faire taire les voix des peuples autochtones.\u00a0\u00bb    &nbsp;<\/p>\n<p>Doley et d&rsquo;autres critiques craignent surtout les cas d&rsquo;assassinats sous la garde de la police au cours des deux derni\u00e8res ann\u00e9es. Il a activement soulev\u00e9 des questions sur des plateformes nationales et internationales et a \u00e9t\u00e9 victime de la criminalisation, en particulier des poursuites strat\u00e9giques contre la participation publique, plus connues sous le nom de poursuites-b\u00e2illons, pour le dissuader d&rsquo;\u00e9lever la voix. Les poursuites SLAPP dont il a fait l&rsquo;objet concernaient des personnes qui lui sont proches. La situation difficile dans laquelle se trouve Pranab Doley met en lumi\u00e8re le mod\u00e8le de conservation de la forteresse indienne, qui se conforme aux zones prot\u00e9g\u00e9es o\u00f9 les \u00e9cosyst\u00e8mes sont libres de toute interaction humaine.   &nbsp;<\/p>\n<p>Ce mod\u00e8le de conservation est fond\u00e9 sur une approche coloniale et discriminatoire et a \u00e9t\u00e9 la principale raison de la violation des droits des peuples autochtones et des autres communaut\u00e9s locales vivant dans ces r\u00e9gions. Ils ont \u00e9t\u00e9 pris pour cible et rendus responsables de la perte d&rsquo;\u00e9cosyst\u00e8mes et de la destruction de l&rsquo;environnement, malgr\u00e9 leur lutte constante pour la sauvegarde des for\u00eats et de la biodiversit\u00e9 contre les entreprises et l&rsquo;\u00c9tat. &nbsp;<\/p>\n<p>\u00ab\u00a0Nous, les peuples autochtones, avons fait d&rsquo;\u00e9normes sacrifices pour prot\u00e9ger l&rsquo;environnement alors que les int\u00e9r\u00eats commerciaux et corporatifs \u00e0 l&rsquo;int\u00e9rieur des for\u00eats, tels que l&rsquo;exploitation mini\u00e8re, sont commod\u00e9ment ignor\u00e9s par le gouvernement\u00a0\u00bb, d\u00e9clare M. Doley. Il esp\u00e8re ardemment que les nombreux d\u00e9guisements utilis\u00e9s, tels que la \u00ab\u00a0conservation de la vie sauvage\u00a0\u00bb ou la \u00ab\u00a0conservation de la biodiversit\u00e9\u00a0\u00bb, cesseront de d\u00e9truire les vies, les moyens de subsistance, la culture et les syst\u00e8mes \u00e9cologiques des populations autochtones vivant m\u00eame au-del\u00e0 et autour des zones prot\u00e9g\u00e9es d\u00e9clar\u00e9es. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tigres, conservation et droits des peuples autochtones Derri\u00e8re la conservation active et la renaissance de la population de tigres en d\u00e9clin en Inde, persistent des probl\u00e8mes et des cas d&rsquo;anomalies, d&rsquo;irr\u00e9gularit\u00e9s et de violations flagrantes des droits, de..<\/p>\n","protected":false},"author":1,"featured_media":85547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[279],"tags":[293],"class_list":["post-85546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-et-caracteristiques","tag-ldsf"],"_links":{"self":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/85546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/comments?post=85546"}],"version-history":[{"count":2,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/85546\/revisions"}],"predecessor-version":[{"id":85587,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/85546\/revisions\/85587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media\/85547"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media?parent=85546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/categories?post=85546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/tags?post=85546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}