{"id":86762,"date":"2022-04-25T12:34:25","date_gmt":"2022-04-25T12:34:25","guid":{"rendered":"https:\/\/iprights.org\/2022\/04\/25\/note-dinformation-principes-directeurs-des-nations-unies-et-protection-des-droits-des-peuples-autochtones-dans-le-contexte-des-activites-des-entreprises\/"},"modified":"2026-05-12T15:01:32","modified_gmt":"2026-05-12T15:01:32","slug":"note-dinformation-principes-directeurs-des-nations-unies-et-protection-des-droits-des-peuples-autochtones-dans-le-contexte-des-activites-des-entreprises","status":"publish","type":"post","link":"https:\/\/iprights.org\/fr\/2022\/04\/25\/note-dinformation-principes-directeurs-des-nations-unies-et-protection-des-droits-des-peuples-autochtones-dans-le-contexte-des-activites-des-entreprises\/","title":{"rendered":"Note d\u2019information : Principes directeurs des Nations Unies et protection des droits des peuples autochtones dans le contexte des activit\u00e9s des entreprises"},"content":{"rendered":"<p>Chers toutes et tous, <\/p>\n<p>J\u2019ai le plaisir de partager avec vous cette note d\u2019information d\u2019Indigenous Peoples Rights International (IPRI) sur les peuples autochtones, les droits humains et les activit\u00e9s des entreprises. Elle a \u00e9t\u00e9 pr\u00e9par\u00e9e comme notre contribution \u00e0 la 21e session de l\u2019Instance permanente des Nations Unies, dont le th\u00e8me est \u00abPeuples autochtones, entreprises, autonomie et principes des droits humains relatifs \u00e0 la diligence raisonnable, y compris le consentement libre, pr\u00e9alable et \u00e9clair\u00e9\u00bb.  <\/p>\n<p>Cette note d\u2019information fournit des \u00e9l\u00e9ments sur les Principes directeurs des Nations Unies relatifs aux entreprises et aux droits de l\u2019homme (UNGP), la feuille de route UNGP+10, ainsi que sur les travaux du Groupe de travail des Nations Unies sur les entreprises et les droits de l\u2019homme (WGBHR) en lien avec les droits des peuples autochtones.<br \/>Elle pr\u00e9sente \u00e9galement certaines initiatives men\u00e9es par l\u2019IPRI et ses organisations partenaires afin de renforcer la mise en \u0153uvre des UNGP, d\u2019assurer le respect de la D\u00e9claration des Nations Unies sur les droits des peuples autochtones (UNDRIP) et de contribuer \u00e0 mettre fin \u00e0 la violence et \u00e0 la criminalisation des peuples autochtones dans le contexte des activit\u00e9s des entreprises. <\/p>\n<p>Respectueusement,<br \/>Joan Carling<br \/>Directrice ex\u00e9cutive<br \/>Indigenous Peoples Rights International (IPRI)<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/iprights.org\/wp-content\/uploads\/2025\/11\/Briefing-UNGPs-and-the-protection-of-IPR.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9l\u00e9chargez le document PDF complet<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chers toutes et tous, J\u2019ai le plaisir de partager avec vous cette note d\u2019information d\u2019Indigenous Peoples Rights International (IPRI) sur les peuples autochtones, les droits humains et les activit\u00e9s des entreprises. Elle a \u00e9t\u00e9 pr\u00e9par\u00e9e comme notre contribution..<\/p>\n","protected":false},"author":2,"featured_media":86763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[370,302],"tags":[348],"class_list":["post-86762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entreprises-et-droits-de-lhomme","category-ressources","tag-empresas-y-derechos-humanos"],"_links":{"self":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/86762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/comments?post=86762"}],"version-history":[{"count":5,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/86762\/revisions"}],"predecessor-version":[{"id":87653,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/86762\/revisions\/87653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media\/86763"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media?parent=86762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/categories?post=86762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/tags?post=86762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}