{"id":87490,"date":"2020-12-07T18:58:06","date_gmt":"2020-12-07T18:58:06","guid":{"rendered":"https:\/\/iprights.org\/2020\/12\/07\/philippines-une-organisation-internationale-de-defense-des-droits-des-peuples-autochtones-appelle-a-labandon-des-accusations-fabriquees-de-toutes-pieces-et-a-la-liberation-immediate-de-betty\/"},"modified":"2020-12-07T18:58:06","modified_gmt":"2020-12-07T18:58:06","slug":"philippines-une-organisation-internationale-de-defense-des-droits-des-peuples-autochtones-appelle-a-labandon-des-accusations-fabriquees-de-toutes-pieces-et-a-la-liberation-immediate-de-betty","status":"publish","type":"post","link":"https:\/\/iprights.org\/fr\/2020\/12\/07\/philippines-une-organisation-internationale-de-defense-des-droits-des-peuples-autochtones-appelle-a-labandon-des-accusations-fabriquees-de-toutes-pieces-et-a-la-liberation-immediate-de-betty\/","title":{"rendered":"Philippines: une organisation internationale de d\u00e9fense des droits des peuples autochtones appelle \u00e0 l\u2019abandon des accusations fabriqu\u00e9es de toutes pi\u00e8ces et \u00e0 la lib\u00e9ration imm\u00e9diate de Betty Belen."},"content":{"rendered":"<div>\n<p>Indigenous Peoples Rights International (IPRI) a exprim\u00e9 sa profonde pr\u00e9occupation concernant l\u2019arrestation ill\u00e9gale et la d\u00e9tention continue de Beatrice \u00ab Betty \u00bb Belen, une femme autochtone issue de la communaut\u00e9 Uma de la Cordill\u00e8re, aux Philippines.<\/p>\n<p>Selon un rapport soumis \u00e0 Indigenous Peoples Rights International (IPRI), des \u00e9l\u00e9ments combin\u00e9s de la Police nationale philippine (PNP), de la 503e brigade d\u2019infanterie des Forces arm\u00e9es des Philippines (AFP) et du Criminal Investigation and Detection Group (CIDG) ont ex\u00e9cut\u00e9 des mandats de perquisition visant au moins onze personnes, dont Belen, \u00e0 Lower et Western Uma, Lubuagan, Kalinga, le 25 octobre 2020 \u00e0 4 heures du matin.<\/p>\n<p> Les autorit\u00e9s auraient saisi trois grenades \u00e0 fusil au domicile de Belen. Cependant, il a \u00e9t\u00e9 rapport\u00e9 \u00e0 Indigenous Peoples Rights International (IPRI) que la perquisition a \u00e9t\u00e9 men\u00e9e sans t\u00e9moins ind\u00e9pendants et sans la participation des responsables du village. <\/p>\n<p>La fabrication de preuves visant \u00e0 criminaliser les militants autochtones devient d\u00e9sormais monnaie courante afin de semer la peur et de d\u00e9mobiliser celles et ceux qui se trouvent en premi\u00e8re ligne dans la d\u00e9fense des terres et des ressources des peuples autochtones.<\/p>\n<p>Belen, membre de Innabuyog \u2013 An Alliance of Indigenous Women\u2019s Organizations in the Cordillera, est une fervente d\u00e9fenseuse de l\u2019environnement et des droits des peuples autochtones, ainsi qu\u2019une agente de sant\u00e9 communautaire qui sert inlassablement sa communaut\u00e9. Elle a consacr\u00e9 sa vie \u00e0 la protection des terres ancestrales et \u00e0 la d\u00e9fense des droits des peuples autochtones. Cette attaque \u00e0 son encontre constitue une atteinte non seulement au mouvement autochtone de la Cordill\u00e8re, mais aussi aux femmes qui se mobilisent pour les droits humains.  <\/p>\n<p>Beatrice Belen faisait partie des personnes ayant men\u00e9 un barrage contre le projet g\u00e9othermique de la soci\u00e9t\u00e9 Chevron Energy dans la province de Kalinga en 2012. En 2018, elle a re\u00e7u le <g id=\"gid_0\">Gawad Bayani ng Kalikasan <\/g>(Prix du h\u00e9ros de l\u2019environnement) pour son engagement in\u00e9branlable dans la d\u00e9fense de leurs terres ancestrales. <\/p>\n<p>Avant son arrestation, elle avait d\u00e9j\u00e0 \u00e9t\u00e9 victime de harc\u00e8lement et d\u2019intimidations de la part d\u2019agents de l\u2019\u00c9tat depuis 2015. Elle \u00e9tait accus\u00e9e d\u2019avoir h\u00e9berg\u00e9 et accueilli des membres de la Nouvelle Arm\u00e9e du Peuple (New People\u2019s Army), un groupe arm\u00e9 qualifi\u00e9 d\u2019insurg\u00e9 par le gouvernement des Philippines. <\/p>\n<p>L\u2019arrestation de Belen a gravement affect\u00e9 sa famille et sa communaut\u00e9. Avant son arrestation, elle aidait sa famille dans les travaux agricoles et la fabrication de balais souples, tout en accompagnant ses deux petits-enfants dans leur apprentissage \u00e0 distance. <\/p>\n<p>Elle est actuellement d\u00e9tenue \u00e0 la prison municipale de Tabuk. Aucune affaire n\u2019a encore \u00e9t\u00e9 officiellement engag\u00e9e contre elle, mais elle fait l\u2019objet d\u2019une enqu\u00eate pr\u00e9liminaire pour possession ill\u00e9gale pr\u00e9sum\u00e9e d\u2019explosifs. Elle restera incarc\u00e9r\u00e9e pendant toute la dur\u00e9e de l\u2019enqu\u00eate.  <\/p>\n<p>\u00abCe qui est arriv\u00e9 \u00e0 Belen peut arriver \u00e0 d\u2019autres femmes qui d\u00e9noncent ouvertement les menaces pesant sur nos terres ancestrales ici dans la Cordill\u00e8re, et en r\u00e9alit\u00e9 \u00e0 toute personne exprimant son opposition aux politiques gouvernementales nuisibles aux droits et au bien-\u00eatre de la population. Cela ne devrait pas \u00eatre le cas\u00bb, a d\u00e9clar\u00e9 Innabuyog \u2013 An Alliance of Indigenous Women\u2019s Organizations in the Cordillera dans un communiqu\u00e9.<\/p>\n<p>\u00abLe militantisme n\u2019est pas du terrorisme. Le militantisme cherche \u00e0 apporter des changements positifs, en particulier pour les secteurs marginalis\u00e9s, notamment les femmes et les peuples autochtones. Ce n\u2019est pas un acte de terrorisme. Nous appelons nos cons\u0153urs \u00e0 d\u00e9noncer ces violations de nos droits humains garantis par la Constitution\u00bb, ont-elles ajout\u00e9.<\/p>\n<p>La codirectrice de Indigenous Peoples Rights International (IPRI) et ancienne rapporteuse sp\u00e9ciale des Nations Unies sur les droits des peuples autochtones, Victoria Tauli-Corpuz, a soulign\u00e9 l\u2019obligation du gouvernement des Philippines de prot\u00e9ger et de respecter les droits des peuples autochtones.<\/p>\n<p>\u00abLes peuples autochtones ne devraient pas \u00eatre pris pour cible pour avoir d\u00e9fendu leurs droits ni pour avoir exerc\u00e9 leur droit \u00e0 l\u2019autod\u00e9termination sur leurs terres, territoires et ressources, ainsi qu\u2019au consentement libre, pr\u00e9alable et \u00e9clair\u00e9. Tous les \u00c9tats, y compris le gouvernement philippin, devraient comprendre et reconna\u00eetre la sp\u00e9cificit\u00e9 des droits des peuples autochtones\u00bb, a d\u00e9clar\u00e9 Victoria Tauli-Corpuz.<\/p>\n<p>Indigenous Peoples Rights International (IPRI) se joint \u00e0 d\u2019autres organisations de peuples autochtones pour exiger du gouvernement des Philippines la lib\u00e9ration imm\u00e9diate de Belen ainsi que l\u2019abandon des accusations fabriqu\u00e9es de toutes pi\u00e8ces port\u00e9es contre elle.<\/p>\n<p>Pour toute demande d\u2019entretien, veuillez envoyer un courriel \u00e0:<br \/>Secr\u00e9tariat mondial de l\u2019Indigenous Peoples Rights International: <span id=\"cloak9345fd5f5e9a4e8244137571bdf56e96\"><a href=\"mailto:ipri@indigenousrightsinternational.org\">ipri@indigenousrightsinternational.org<\/a><\/span>, <span id=\"cloak655bb75fc5ee87fe35ed7ccba30ec038\"><a href=\"mailto:IPRIsecretariat@gmail.com\">IPRIsecretariat@gmail.com<\/a><\/span><br \/>Joan Carling: <span id=\"cloak74d469c3b22a7ed2017c31267f29788e\"><a href=\"mailto:joan.carling77@gmail.com\">joan.carling77@gmail.com<\/a><\/span><br \/>Vicky Tauli-Corpuz: <span id=\"cloak34e987f35233e6b00434748d7d7be0f5\"><a href=\"mailto:vicky@tebtebba.org\">vicky@tebtebba.org<\/a><\/span><\/p>\n<p>T\u00e9l\u00e9chargez la pi\u00e8ce jointe pour lire l\u2019article complet.<\/p>\n<p>T\u00e9l\u00e9chargement(s)<br \/> <a href=\"https:\/\/test.iprights.org\/images\/resources\/downloadables\/Press-Release_-International-Indigenous-Peoples-rights-group-calls-for-dropping-of-trumped-up-charges-immediate-release-of-Betty-Belen.pdf\" target=\"_blank\" rel=\"noopener\">Press Release_ International Indigenous Peoples\u2019 rights group calls for dropping of trumped-up charges, immediate release of Betty Belen.pdf (pdf, 117KB)<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Indigenous Peoples Rights International (IPRI) a exprim\u00e9 sa profonde pr\u00e9occupation concernant l\u2019arrestation ill\u00e9gale et la d\u00e9tention continue de Beatrice \u00ab Betty \u00bb Belen, une femme autochtone issue de la communaut\u00e9 Uma de la Cordill\u00e8re, aux Philippines. Selon un..<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[279],"tags":[],"class_list":["post-87490","post","type-post","status-publish","format-standard","hentry","category-actualites-et-caracteristiques"],"_links":{"self":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/87490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/comments?post=87490"}],"version-history":[{"count":0,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/posts\/87490\/revisions"}],"wp:attachment":[{"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/media?parent=87490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/categories?post=87490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iprights.org\/fr\/wp-json\/wp\/v2\/tags?post=87490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}